{"id":9,"date":"2023-04-27T00:00:00","date_gmt":"2023-04-27T00:00:00","guid":{"rendered":"https:\/\/cota1.wpengine.com\/cotaforalohi\/?p=9"},"modified":"2023-04-27T00:00:00","modified_gmt":"2023-04-27T00:00:00","slug":"alohi","status":"publish","type":"gallery","link":"https:\/\/cota.org\/cotaforalohi\/photos\/alohi\/","title":{"rendered":"Alohi"},"content":{"rendered":"<div id=\"block-block_a2857fc73245bb2cb7a367929f8652af\" class=\"block block--photo-gallery \">\n\t\t\t\t\t\t<div id=\"dialog-source\">\n\t\t\t\t<button class=\"lightbox-trigger\" data-slide=\"0\" data-a11y-dialog-show=\"lightbox-carousel\" aria-label=\"Open image carousel in dialog window.\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-150x150.jpg 150w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-590x590.jpg 590w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-390x390.jpg 390w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-790x790.jpg 790w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-120x120.jpg 120w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-600x600.jpg 600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t<\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div id=\"dialog-source\">\n\t\t\t\t<button class=\"lightbox-trigger\" data-slide=\"1\" data-a11y-dialog-show=\"lightbox-carousel\" aria-label=\"Open image carousel in dialog window.\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi3-150x150.jpg 150w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi3-390x390.jpg 390w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi3-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t<\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div id=\"dialog-source\">\n\t\t\t\t<button class=\"lightbox-trigger\" data-slide=\"2\" data-a11y-dialog-show=\"lightbox-carousel\" aria-label=\"Open image carousel in dialog window.\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi2-150x150.jpg 150w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi2-590x590.jpg 590w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi2-390x390.jpg 390w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi2-120x120.jpg 120w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi2-600x600.jpg 600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t<\/button>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div\n\t\tid=\"lightbox-carousel\"\n\t\taria-labelledby=\"photo-lightbox\"\n\t\tclass=\"dialog-container\"\n\t\taria-hidden=\"true\"\n\t\t>\n\n\t\t<div class=\"dialog-overlay\" data-a11y-dialog-hide><\/div>\n\t\t<div class=\"slick-nav\">\n\t\t\t<span class=\"slide-index\"><\/span>\n\t\t<\/div>\n\t\t<button class=\"close-dialog\" type=\"button\" data-a11y-dialog-hide aria-label=\"Close dialog\">&times;<\/button>\n\t\t<div class=\"dialog-content\" role=\"document\">\n\t\t\t<h2 class=\"screen-reader-text\" id=\"photo-lightbox\">Photo lightbox<\/h2>\n\t\t\t<div class=\"carousel\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel--image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1233\" height=\"1800\" src=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1.jpg 1233w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-206x300.jpg 206w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-701x1024.jpg 701w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-768x1121.jpg 768w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi1-1052x1536.jpg 1052w\" sizes=\"auto, (max-width: 1233px) 100vw, 1233px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"carousel--image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"582\" height=\"590\" src=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi3.jpg 582w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi3-296x300.jpg 296w\" sizes=\"auto, (max-width: 582px) 100vw, 582px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"carousel--image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"687\" height=\"916\" src=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi2.jpg 687w, https:\/\/cota.org\/cotaforalohi\/wp-content\/uploads\/sites\/3526\/2023\/10\/Alohi2-225x300.jpg 225w\" sizes=\"auto, (max-width: 687px) 100vw, 687px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-9","gallery","type-gallery","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cota.org\/cotaforalohi\/wp-json\/wp\/v2\/gallery\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cota.org\/cotaforalohi\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/cota.org\/cotaforalohi\/wp-json\/wp\/v2\/types\/gallery"}],"wp:attachment":[{"href":"https:\/\/cota.org\/cotaforalohi\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}